{"id":961,"count":1,"description":"","link":"http:\/\/motorcyclecolorado.com\/blog\/tag\/motorcycle-riding-in-january\/","name":"motorcycle riding in January","slug":"motorcycle-riding-in-january","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/tags\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/posts?tags=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}