{"id":747,"count":2,"description":"","link":"http:\/\/motorcyclecolorado.com\/blog\/tag\/lookout-mountain\/","name":"Lookout Mountain","slug":"lookout-mountain","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/tags\/747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/posts?tags=747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}