{"id":720,"count":1,"description":"","link":"http:\/\/motorcyclecolorado.com\/blog\/tag\/cold-springs-campground\/","name":"Cold Springs Campground","slug":"cold-springs-campground","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/tags\/720","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/posts?tags=720"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}