{"id":421,"count":1,"description":"","link":"http:\/\/motorcyclecolorado.com\/blog\/tag\/lobbying\/","name":"lobbying","slug":"lobbying","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/tags\/421","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/posts?tags=421"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}