{"id":12,"count":27,"description":"","link":"http:\/\/motorcyclecolorado.com\/blog\/category\/helmet-laws\/","name":"Helmet Laws","slug":"helmet-laws","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/categories\/12","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/motorcyclecolorado.com\/blog\/wp-json\/wp\/v2\/posts?categories=12"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}